{"id":1069,"date":"2026-05-11T10:48:56","date_gmt":"2026-05-11T10:48:56","guid":{"rendered":"https:\/\/panafgeo.eurogeosurveys.org\/uganda\/"},"modified":"2026-05-13T12:13:29","modified_gmt":"2026-05-13T12:13:29","slug":"uganda","status":"publish","type":"activity","link":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/uganda\/","title":{"rendered":"Uganda"},"content":{"rendered":"<p data-start=\"7328\" data-end=\"7622\">A Country Window do PanAfGeo+ no Uganda apoia a promo\u00e7\u00e3o do potencial mineral do Uganda, com enfoque em dep\u00f3sitos numa fase avan\u00e7ada de potencial desenvolvimento, em conformidade com normas nacionais, africanas e internacionais em mat\u00e9ria ambiental, social, de governa\u00e7\u00e3o e requisitos t\u00e9cnicos.<\/p>\n<p data-start=\"7624\" data-end=\"8035\">As atividades incluem recolha de dados atrav\u00e9s da facilita\u00e7\u00e3o e realiza\u00e7\u00e3o da avalia\u00e7\u00e3o de dep\u00f3sitos cr\u00edticos e outros dep\u00f3sitos minerais do Uganda, bem como trabalhos de explora\u00e7\u00e3o sempre que necess\u00e1rio. Estas a\u00e7\u00f5es refor\u00e7am simultaneamente as capacidades t\u00e9cnicas e a visibilidade da Directorate of Geological Survey and Mines (DGSM), integrada no Minist\u00e9rio da Energia e do Desenvolvimento Mineral do Uganda.<\/p>\n<p data-start=\"8037\" data-end=\"8303\">O programa contribui para o refor\u00e7o das capacidades de explora\u00e7\u00e3o e de outras compet\u00eancias do Departamento de Servi\u00e7os Geol\u00f3gicos da DGSM, bem como para a promo\u00e7\u00e3o de ocorr\u00eancias minerais cr\u00edticas e outros dep\u00f3sitos j\u00e1 avaliados, com vista \u00e0 atra\u00e7\u00e3o de investimento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Respons\u00e1vel pelo Country Window<\/strong><\/p>\n<ul>\n<li>Servi\u00e7o Geol\u00f3gico da Eslov\u00e9nia (GeoZS)<\/li>\n<li>Dr Slavko Vekoslav \u0160olar, Conselheiro para Mat\u00e9rias-Primas<\/li>\n<li><a href=\"mailto:slavko.solar@geo-zs.si\">slavko.solar@geo-zs.si<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A Country Window do PanAfGeo+ no Uganda apoia a promo\u00e7\u00e3o do potencial mineral do Uganda, com enfoque em dep\u00f3sitos numa fase avan\u00e7ada de potencial desenvolvimento, em conformidade com normas nacionais, africanas e internacionais em mat\u00e9ria ambiental, social, de governa\u00e7\u00e3o e requisitos t\u00e9cnicos. As atividades incluem recolha de dados atrav\u00e9s da facilita\u00e7\u00e3o e realiza\u00e7\u00e3o da avalia\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"featured_media":214,"template":"","class_list":["post-1069","activity","type-activity","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/activity\/1069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/activity"}],"about":[{"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/types\/activity"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/media\/214"}],"wp:attachment":[{"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=1069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}