{"id":1005,"date":"2026-05-04T12:59:00","date_gmt":"2026-05-04T12:59:00","guid":{"rendered":"https:\/\/panafgeo.eurogeosurveys.org\/media-coverage\/panafgeo-featured-by-unesco-geoheritage-training-session-in-kenyas-great-rift-valley\/"},"modified":"2026-05-04T13:19:23","modified_gmt":"2026-05-04T13:19:23","slug":"panafgeo-featured-by-unesco-geoheritage-training-session-in-kenyas-great-rift-valley","status":"publish","type":"media-coverage","link":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/media-coverage\/panafgeo-featured-by-unesco-geoheritage-training-session-in-kenyas-great-rift-valley\/","title":{"rendered":"PanAfGeo+ destacado pela UNESCO: forma\u00e7\u00e3o sobre geoss\u00edtios no Vale do Rift no Qu\u00e9nia"},"content":{"rendered":"<p>As atividades do PanAfGeo+ foram destacadas pela UNESCO, evidenciando uma sess\u00e3o de forma\u00e7\u00e3o WP5 dedicada ao geoss\u00edtio e \u00e0 geoconserva\u00e7\u00e3o, realizada no Vale do Rift, no Qu\u00e9nia.<\/p>\n<p>A forma\u00e7\u00e3o reuniu geocientistas, autoridades locais e comunidades, com o objetivo de refor\u00e7ar as capacidades na identifica\u00e7\u00e3o, documenta\u00e7\u00e3o e conserva\u00e7\u00e3o do patrim\u00f3nio geol\u00f3gico, promovendo simultaneamente a liga\u00e7\u00e3o entre geoci\u00eancias, desenvolvimento sustent\u00e1vel e envolvimento local.<\/p>\n<p>Esta publica\u00e7\u00e3o evidencia a import\u00e2ncia do geoss\u00edtio no \u00e2mbito do programa PanAfGeo+ e a sua contribui\u00e7\u00e3o para os esfor\u00e7os internacionais em mat\u00e9ria de conserva\u00e7\u00e3o e gest\u00e3o sustent\u00e1vel dos recursos.<\/p>\n<p data-start=\"613\" data-end=\"804\">Mais informa\u00e7\u00f5es <a href=\"https:\/\/www.unesco.org\/en\/articles\/what-geological-heritage-and-conservation-training-looks-kenyas-great-rift-valley\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As atividades do PanAfGeo+ foram destacadas pela UNESCO, evidenciando uma sess\u00e3o de forma\u00e7\u00e3o WP5 dedicada ao geoss\u00edtio e \u00e0 geoconserva\u00e7\u00e3o, realizada no Vale do Rift, no Qu\u00e9nia. A forma\u00e7\u00e3o reuniu geocientistas, autoridades locais e comunidades, com o objetivo de refor\u00e7ar as capacidades na identifica\u00e7\u00e3o, documenta\u00e7\u00e3o e conserva\u00e7\u00e3o do patrim\u00f3nio geol\u00f3gico, promovendo simultaneamente a liga\u00e7\u00e3o entre [&hellip;]<\/p>\n","protected":false},"featured_media":1003,"template":"","media_category":[52,51],"class_list":["post-1005","media-coverage","type-media-coverage","status-publish","has-post-thumbnail","hentry","media_category-formacoes","media_category-investigacao"],"acf":[],"_links":{"self":[{"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/media-coverage\/1005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/media-coverage"}],"about":[{"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/types\/media-coverage"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/media\/1003"}],"wp:attachment":[{"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=1005"}],"wp:term":[{"taxonomy":"media_category","embeddable":true,"href":"https:\/\/panafgeo.eurogeosurveys.org\/pt-pt\/wp-json\/wp\/v2\/media_category?post=1005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}